{"id":905,"date":"2025-02-24T19:51:22","date_gmt":"2025-02-24T18:51:22","guid":{"rendered":"https:\/\/omsfel.fr\/?p=905"},"modified":"2025-02-27T20:02:24","modified_gmt":"2025-02-27T19:02:24","slug":"piece-de-theatre-de-la-troupe-des-messagers-de-anton-tchekhov","status":"publish","type":"post","link":"https:\/\/omsfel.fr\/index.php\/2025\/02\/24\/piece-de-theatre-de-la-troupe-des-messagers-de-anton-tchekhov\/","title":{"rendered":"Pi\u00e8ce de Th\u00e9\u00e2tre de la troupe des  Messagers de Anton TChekhov:"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L&rsquo;Ours &#8211; <\/strong><strong>La Demande en mariage &#8211; Le Chant du Cygne<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Samedi 8 MARS \u00e0 20 h <\/strong> &#8211; Salle Jean-Ferrat Mign\u00e9-Auxances <br><br>L&rsquo;ASSOCIATION OMSFEL de Mign\u00e9 Auxances organise avec la troupe \u00a0\u00bb DES MESSAGERS\u00a0\u00bb  de Ciss\u00e9, une repr\u00e9sentation th\u00e9\u00e2trale : TCHEKOV<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous trouverez l&rsquo;affiche qui vous donne les informations n\u00e9cessaires pour nous rejoindre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LES FONDS SERONT ENTIEREMENT REVERSES \u00e0 l&rsquo;ASSOCIATION DES ECOLIERS DU NEPAL qui \u0153uvrent pour l&rsquo;\u00e9ducation et la formation professionnelle aupr\u00e8s des jeunes d\u00e9favoris\u00e9s des villages n\u00e9palais<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tarif plein : 10 \u20ac  adulte  &#8211;   7 \u20ac \u00e9tudiants, demandeurs d&#8217;emploi<br><br>R\u00e9servation: 06.71.74.60.96 &#8211;   lesecoliersdunepal@gmail.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" class=\"wp-image-819\" style=\"width: NaNpx;\" src=\"https:\/\/omsfel.fr\/wp-content\/uploads\/2024\/10\/Affiche-TPP-2024-Migne-Auxances-reservation-2.pdf\" alt=\"\">nous vous attendons nombreux\u00a0&#8211; un pot offert par OMSFEL et LES ECOLIERS vous attend \u00e0 la fin de la soir\u00e9e<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image-724x1024.png\" alt=\"\" class=\"wp-image-907\" srcset=\"https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image-724x1024.png 724w, https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image-212x300.png 212w, https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image-768x1086.png 768w, https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image-1086x1536.png 1086w, https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image-1448x2048.png 1448w, https:\/\/omsfel.fr\/wp-content\/uploads\/2025\/02\/image.png 1654w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Ours &#8211; La Demande en mariage &#8211; Le Chant du Cygne Samedi 8 MARS \u00e0 20 h &#8211; Salle Jean-Ferrat Mign\u00e9-Auxances L&rsquo;ASSOCIATION OMSFEL de Mign\u00e9 Auxances organise avec la troupe \u00a0\u00bb DES MESSAGERS\u00a0\u00bb de Ciss\u00e9, une repr\u00e9sentation th\u00e9\u00e2trale : TCHEKOV Vous trouverez l&rsquo;affiche qui vous donne les informations n\u00e9cessaires pour nous rejoindre. LES FONDS SERONT [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spectacle"],"_links":{"self":[{"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/posts\/905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/comments?post=905"}],"version-history":[{"count":7,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/posts\/905\/revisions"}],"predecessor-version":[{"id":915,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/posts\/905\/revisions\/915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/media\/911"}],"wp:attachment":[{"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/media?parent=905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/categories?post=905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/omsfel.fr\/index.php\/wp-json\/wp\/v2\/tags?post=905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}